{"id":6112,"date":"2022-04-14T11:27:53","date_gmt":"2022-04-14T03:27:53","guid":{"rendered":"https:\/\/easyparcel.com\/?page_id=6112"},"modified":"2026-06-11T10:03:37","modified_gmt":"2026-06-11T02:03:37","slug":"airpak","status":"publish","type":"page","link":"https:\/\/easyparcel.com\/sg\/easytrack\/airpak\/","title":{"rendered":"Airpak Express"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6112\" class=\"elementor elementor-6112\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15b2345 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"15b2345\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;triangle&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500.2,94.7L0,0v100h1000V0L500.2,94.7z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a2f62d0 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"a2f62d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b37c71 elementor-widget elementor-widget-image\" data-id=\"3b37c71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"140\" src=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2022\/08\/Airpak_Express.png\" class=\"attachment-full size-full wp-image-18169\" alt=\"Airpak Express Courier Tracking logo\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92b5aa1 elementor-widget elementor-widget-heading\" data-id=\"92b5aa1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_tilt_effect&quot;:&quot;yes&quot;,&quot;motion_fx_tilt_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]}}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Enter Your Airpak Express Tracking Number<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a4d3f6 elementor-widget__width-initial elementor-widget elementor-widget-easyparcel_track\" data-id=\"1a4d3f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"easyparcel_track.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<form class=\"easyparcel-widget easyparcel-track\">\n    <div class=\"card border-0\">\n        <div class=\"card-body text-center\">\n                            <img decoding=\"async\" class=\"courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Airpak_Express.jpg\">\n                <h3 class=\"card-title courier-name\">Track Airpak Express Shipments<\/h3>\n\n                                    <div class=\"courier-info\">\n                        \n                                                    <div class=\"courier-info-item\">\n                                <i class=\"fa-solid fa-earth text-xs-asia\"><\/i>\n                                <a href=\"http:\/\/www.airpak-express.com\/\" target=\"_blank\">http:\/\/www.airpak-express.com\/<\/a>\n                            <\/div>\n                        \n                                                    <div class=\"courier-info-item\">\n                                <i class=\"fa-solid fa-envelope text-xs\"><\/i>\n                                <a href=\"mailto: cs.manager@airpak-express.com \">cs.manager@airpak-express.com <\/a>\n                            <\/div>\n                                            <\/div>\n                            \n            <hr>\n\n            <input type=\"hidden\" name=\"country\" value=\"SG\">\n            <input type=\"hidden\" name=\"webapp_url\" value=\"https:\/\/app.easyparcel.com\/sg\/en\/\">\n            <input type=\"hidden\" name=\"total_tracking\" value=\"65531926\">\n\n                            <input type=\"hidden\" name=\"courier\" value=\"airpak\">\n            \n            <div class=\"track-area\">\n                <textarea id=\"awb\" class=\"form-control\" rows=\"15\" aria-required=\"true\" placeholder=\"Enter up to 15 tracking numbers \/ EasyParcel order number\"><\/textarea>\n            <\/div>\n\n            <p class=\"track-notes\">Separate with a semicolon (;) or return (enter).<\/p>\n\n\n            <button type=\"submit\" class=\"btn btn-primary\">\n                <i class=\"fa-solid fa-location-dot\"><\/i>\n                Track Parcel            <\/button>\n        <\/div>\n    <\/div>\n<\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0cd0e4 animated-icon elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f0cd0e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#track-your-parcel\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-circle-down\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8420c0 elementor-widget elementor-widget-menu-anchor\" data-id=\"c8420c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"track-your-parcel\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-699162a e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"699162a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc46ae9 elementor-widget elementor-widget-shortcode\" data-id=\"fc46ae9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"43657\" class=\"elementor elementor-43657\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-801c6ca e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"801c6ca\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;shape_divider_bottom&quot;:&quot;triangle&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,98.9L0,6.1V0h1000v6.1L500,98.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-092c191 elementor-widget elementor-widget-heading\" data-id=\"092c191\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Track Your Parcel With EasyTrack<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b34f702 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"b34f702\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ed93bdb e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"ed93bdb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9976c78 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"9976c78\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"87\" height=\"87\" src=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2023\/09\/EasyTrack-shipments-md.png\" class=\"attachment-full size-full wp-image-44682\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Real-time Tracking<\/h5><p class=\"elementor-image-box-description\">View the latest delivery statuses of all your shipments in one place.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1808a6d e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"1808a6d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1337cd2 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"1337cd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"87\" height=\"87\" src=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2023\/09\/EasyTrack-notify-md.png\" class=\"attachment-full size-full wp-image-44689\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Email Tracking Notification<\/h5><p class=\"elementor-image-box-description\">Notify receiver via email on tracking statuses.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-15e0843 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"15e0843\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c897019 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"c897019\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceIn&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"87\" height=\"87\" src=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2023\/09\/EasyTrack-setting-md.png\" class=\"attachment-full size-full wp-image-44693\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Free Tracking Widget<\/h5><p class=\"elementor-image-box-description\">Free <a href=\"\/my\/widgets\/\" class=\"sg-tracking\" target=\"_blank\">EasyTrack widget<\/a> installation to your website for all-in-one courier tracking.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9554e09 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"9554e09\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-979a619 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"979a619\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceIn&quot;,&quot;_animation_delay&quot;:900}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2023\/09\/EasyTrack-Auto-Detection-by-Tracking-Number.png\" class=\"attachment-full size-full wp-image-44697\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Auto-Detection by Tracking Number<\/h5><p class=\"elementor-image-box-description\">Automatically identify couriers by tracking number format.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a07fe7e e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"a07fe7e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-0e97e0b e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"0e97e0b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc6b3ee elementor-widget elementor-widget-heading\" data-id=\"dc6b3ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">What To Do If <span style=\"color:#f9278e\"> Delayed<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-429e452 elementor-widget elementor-widget-text-editor\" data-id=\"429e452\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>If your shipments didn&#8217;t move as expected, our team is ready to help.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-19e98b0 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"19e98b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-86233bb e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"86233bb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54a8239 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"54a8239\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"560\" src=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2026\/02\/Tracking-Page-New-Section-1-1024x717.webp\" class=\"attachment-large size-large wp-image-109601\" alt=\"\" srcset=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2026\/02\/Tracking-Page-New-Section-1-1024x717.webp 1024w, https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2026\/02\/Tracking-Page-New-Section-1-300x210.webp 300w, https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2026\/02\/Tracking-Page-New-Section-1-768x538.webp 768w, https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2026\/02\/Tracking-Page-New-Section-1.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adf1eef elementor-widget elementor-widget-heading\" data-id=\"adf1eef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Live Chat with our <span style=\"color:#f9278e\"> CS<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1a974b elementor-widget elementor-widget-text-editor\" data-id=\"a1a974b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Get quick help from our Customer Service.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6af87ac start-freshchat primary-filled-sm elementor-widget elementor-widget-button\" data-id=\"6af87ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Start Chat<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b9a534e e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"b9a534e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-95ce128 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"95ce128\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"560\" src=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2026\/02\/2-1-2-1024x717.webp\" class=\"attachment-large size-large wp-image-109606\" alt=\"\" srcset=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2026\/02\/2-1-2-1024x717.webp 1024w, https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2026\/02\/2-1-2-300x210.webp 300w, https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2026\/02\/2-1-2-768x538.webp 768w, https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2026\/02\/2-1-2.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b1d062 elementor-widget elementor-widget-heading\" data-id=\"3b1d062\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Support Ticket via <span style=\"color:#f9278e\"> Email<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0221115 elementor-widget elementor-widget-text-editor\" data-id=\"0221115\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Best for complex cases. We&#8217;ll response as soon as possible.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d0f776 primary-ghost-sm elementor-widget elementor-widget-button\" data-id=\"8d0f776\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/app.easyparcel.com\/contact-us\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Send Ticket<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f3d400 elementor-widget elementor-widget-html\" data-id=\"8f3d400\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\ndocument.addEventListener(\"click\", function (e) {\n  if (e.target.closest(\".start-freshchat\")) {\n    if (window.fcWidget && typeof fcWidget.open === \"function\") {\n      fcWidget.open();\n    }\n    e.preventDefault();\n  }\n});\n<\/script>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ed2296b e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"ed2296b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-86b4801 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"86b4801\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39c1fc8 elementor-widget elementor-widget-heading\" data-id=\"39c1fc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Track and Trace with Singapore Top Courier Tracking Site<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2a5383 elementor-widget elementor-widget-text-editor\" data-id=\"d2a5383\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Effortlessly parcel tracking with ease using EasyTrack&#8217;s auto-detection tracking platform.<\/p><p style=\"text-align: center;\">Our platform covers 80+ courier service companies, including <a class=\"sg-tracking\" href=\"https:\/\/easyparcel.com\/sg\/easytrack\/singpost\/\" target=\"_blank\" rel=\"noopener\">SingPost<\/a>, <a class=\"sg-tracking\" href=\"https:\/\/easyparcel.com\/sg\/easytrack\/qxpress\/\" target=\"_blank\" rel=\"noopener\">TracX Logis<\/a>, <a class=\"sg-tracking\" href=\"https:\/\/easyparcel.com\/sg\/easytrack\/jnt-express\/\" target=\"_blank\" rel=\"noopener\">J&amp;T Express<\/a>, <a class=\"sg-tracking\" href=\"https:\/\/easyparcel.com\/sg\/easytrack\/ninjavan-sg\/\" target=\"_blank\" rel=\"noopener\">Ninja Van<\/a>, <a class=\"sg-tracking\" href=\"https:\/\/easyparcel.com\/sg\/easytrack\/janio\/\" target=\"_blank\" rel=\"noopener\">Janio<\/a>, and more. Stay updated on the status of your international or domestic parcels in Singapore with real-time tracking using your courier tracking number.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f5128f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"1f5128f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4fc1979 elementor-widget elementor-widget-easyparcel_couriers\" data-id=\"4fc1979\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"easyparcel_couriers.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"easyparcel-widget easyparcel-couriers\">\n    <input type=\"hidden\" name=\"country\" value=\"SG\">\n    <input type=\"hidden\" name=\"track_url\" value=\"https:\/\/easyparcel.com\/sg\/easytrack\">\n\n    <div class=\"row\">\n        <div class=\"col-12 col-sm-8\">\n            <h4>Search Your Preferred Courier For Tracking<\/h4>\n        <\/div>\n        <div class=\"col-12 col-sm-4\">\n            <input type=\"text\" class=\"form-control\" placeholder=\"Enter Courier Name\" onkeyup=\"easyparcelCouriers.searchCourier(this)\">\n        <\/div>\n    <\/div>\n\n    <div class=\"\n        courier-items\n        row\n        row-cols-2        row-cols-md-3        row-cols-lg-6        gx-6    \">\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/kex-express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/KEX_Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">KEX Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/after5','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/after5.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">After 5<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/airpak','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Airpak_Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Airpak Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/aladdin','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Aladdin.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Aladdin<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/alfatrex','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Alfatrex.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Alfatrex<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/aramex','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Aramex.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Aramex<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/asiaxpress','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/asiaXpress.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">AsiaXpress<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/best express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/BestExpress.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">BEST Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/carpal','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/CarPal.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">CarPal<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/celsius','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Celcius_Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Celsius<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/citylink','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/City-Link_express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">City-Link Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/cj-logistics','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/CJ_Logistics.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">CJ Logistics<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/collectco','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Collectco.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Collectco<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/cuckoo-express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Cuckoo_Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Cuckoo Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/dd-express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/DD-Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">DD Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/dhlecommerce','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/DHLEC.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">DHL eCommerce<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/dhl-express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/DHL_Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">DHL Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/delivery-perfect_express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/DPE_Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">DPE Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/ecargo','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/ecargo.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Ecargo Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/fedex','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/FedEx.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">FedEx MY<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/fedexsg','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/FedEx.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">FedEx Singapore<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/flash express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Flash_Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Flash Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/fmx','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/FMX.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">FMX<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/gd-express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/GDex.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">GDex<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/golog','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/GoLog.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">GoLog<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/grab-express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Grab_Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Grab Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/istoreisend-isis','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Istore_Isend.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Istore Isend<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/jnt-express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/J&amp;T_Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">J&amp;T Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/jntcargomy','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/J&amp;T_Cargo.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">J&amp;T Cargo<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/janio','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Janio.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Janio<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/jetship','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Jet-Ship_Worldwide.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Jet-Ship Worldwide<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/jne','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/JNE.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">JNE Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/jocom','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Jocom.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Jocom<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/karhoo','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Karhoo.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Karhoo Courier<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/kinkin van','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/KINKINVAN.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">KinKin Van<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/ktmd','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/KTMD.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">KTMD Malaysia<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/lazada-express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Lazada_Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Lazada Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/leopards','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Leopards_Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Leopards Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/line-clear-express-logistics','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Line_Clear_Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Line Clear Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/logistics-worldwide-express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/LWE.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">LWE<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/matdespatch','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/MatDespatch.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">MatDespatch<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/uparcel','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/UParcel.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">uParcel<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/mxpress','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/MXpress.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">MXpress<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/mypostonline','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Mypostonline.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Mypostonline<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/mypoz','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/mypoz.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">MyPoz<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/nearu','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/NearU.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Near U<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/nikos-logistic','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Nikos_Logistic.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Nikos Logistic<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/ninjavan-sg','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/NinjaVan_SG.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">NinjaVan SG<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/ninjavan-my','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/NinjaVan_MY.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">NinjaVan MY<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/park-n-parcel','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Park_N_Parcel.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Park N Parcel<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/pgeon-delivery','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Pgeon.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Pgeon<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/pickupp','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Pickupp.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Pickupp<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/pingu','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/PingU.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Ping U<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/ems','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/EMS.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">EMS<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/melplus','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/MelPlus.png\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Melplus<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/poslaju','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Pos_Laju.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">PosLaju<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/postco','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/PostCo.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Postco<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/redly','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/redly.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Redly Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/eka-sari-lorena','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/ESL_Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">ESL Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/first-logistic','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/First_Logistics.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">First Logistics<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/pcp-express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/PCP_Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">PCP Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/qs','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Quantium.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Quantium Solution<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/rcl','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Red_Carpet_Logistics.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Red Carpet Logistics<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/roadbull','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Roadbull.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Roadbull<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/safe-logistics','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/SAFE_Logistics.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">SAFE Logistics<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/sap-express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/SAP_Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">SAP Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/scg','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/SCG.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">SCG<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/sf-express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/SF_Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">SF Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/shopeexpress','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/ShopeeXpress.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Shopee Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/singapore-post','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Singapore_Post.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Singapore Post<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/singpost','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/SingPost.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">SingPost<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/skynet','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Skynet.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Skynet<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/snt','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/SnT_Global.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">SnT Global<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/spc-worldwide-express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/SPC_Worldwide_Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">SPC Worldwide Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/spx express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/SPX_Express.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">SPX Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/spx xpress','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/SPX_Xpress.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">SPX Xpress<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/surereach','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/sure-reach.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Sure Reach<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/cool-taqbin','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Cool_TAQBIN.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Cool TAQBIN<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/taqbin-my','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/TA-Q-Bin_logo.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">TAQBIN Malaysia<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/teleport','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Teleport.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Teleport<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/thailand-post','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Thailand_Post.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Thailand Post<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/tnt-express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/TNT.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">TNT<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/tracx logis','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/TracX_Logis.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">TracX Logis<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/transprompt','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Transprompt_Freight.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Transprompt Freight<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/ultimate-consolidator','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Ultimate_Consolidators.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Ultimate Consolidators<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/upsmy','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/UPS.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">UPSMY<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/ups','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/UPS.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">UPS<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/urbanfox','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/UrbanFox.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">UrbanFox<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/uts-logistics','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/UTS.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">UTS<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/viamove','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/viamove.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Viamove<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/wepost','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/WePost.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">WePost<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/xdel','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/XDel.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">XDel<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/zepto','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/Zepto.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">Zepto<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/zoomit','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/zoomit.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">ZOOMIT<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"courier-item col\" onclick=\"window.open( 'https:\/\/easyparcel.com\/sg\/easytrack\/zto-express','_self' );\">\n                <div class=\"card h-100\">\n                    <div class=\"courier-logo-wrapper\">\n                        <img decoding=\"async\" class=\"card-img-top courier-logo\" src=\"https:\/\/s3.ap-southeast-1.amazonaws.com\/easyparcel-static\/Public\/source\/general\/img\/easyTrack\/ZTO.jpg\">\n                    <\/div>\n                    <div class=\"card-body\">\n                        <div class=\"card-title courier-name\">ZTO Express<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-47635ba e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"47635ba\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;arrow&quot;}\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M350,10L340,0h20L350,10z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11a89dd elementor-widget elementor-widget-heading\" data-id=\"11a89dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">How Does Our Parcel Tracking Site Work?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ae6593c e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"ae6593c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-094e13f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"094e13f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4935647 elementor-widget elementor-widget-image\" data-id=\"4935647\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"445\" height=\"240\" src=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/my\/wp-content\/uploads\/2022\/06\/easyTrack-step1-md.png\" class=\"attachment-full size-full wp-image-10820\" alt=\"EasyTrack Insert Tracking Number \/ EasyParcel Order Number\" srcset=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/my\/wp-content\/uploads\/2022\/06\/easyTrack-step1-md.png 445w, https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/my\/wp-content\/uploads\/2022\/06\/easyTrack-step1-md-300x162.png 300w\" sizes=\"(max-width: 445px) 100vw, 445px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d060835 elementor-widget elementor-widget-heading\" data-id=\"d060835\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Insert Tracking Number \/ EasyParcel Order Number<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0cc2ee8 elementor-widget elementor-widget-text-editor\" data-id=\"0cc2ee8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Track real-time parcel status by entering tracking number or EasyParcel order numbers with our parcel tracker. It will auto detect couriers by tracking number.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-09f0539 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"09f0539\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab3a556 elementor-widget elementor-widget-image\" data-id=\"ab3a556\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"445\" height=\"241\" src=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/my\/wp-content\/uploads\/2022\/06\/easyTrack-step2-md.png\" class=\"attachment-full size-full wp-image-10826\" alt=\"EasyTrack Get Parcel Tracking Status At A Glance\" srcset=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/my\/wp-content\/uploads\/2022\/06\/easyTrack-step2-md.png 445w, https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/my\/wp-content\/uploads\/2022\/06\/easyTrack-step2-md-300x162.png 300w\" sizes=\"(max-width: 445px) 100vw, 445px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bac613 elementor-widget elementor-widget-heading\" data-id=\"3bac613\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Get Parcel Tracking Status At A Glance<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25aaab6 elementor-widget elementor-widget-text-editor\" data-id=\"25aaab6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Effortlessly track parcel status from 80+ courier companies with our parcel tracker. Enter up to 15 tracking numbers and conveniently view all statuses at a glance.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fd0e9ce e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"fd0e9ce\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f0f883 elementor-widget elementor-widget-image\" data-id=\"4f0f883\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"445\" height=\"241\" src=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/my\/wp-content\/uploads\/2022\/06\/easyTrack-step3-md.png\" class=\"attachment-full size-full wp-image-10834\" alt=\"EasyTrack Notify Receiver Via Email On Tracking Statuses\" srcset=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/my\/wp-content\/uploads\/2022\/06\/easyTrack-step3-md.png 445w, https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/my\/wp-content\/uploads\/2022\/06\/easyTrack-step3-md-300x162.png 300w\" sizes=\"(max-width: 445px) 100vw, 445px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ea0c25 elementor-widget elementor-widget-heading\" data-id=\"9ea0c25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Notify Receiver Via Email On Tracking Statuses<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a9d891 elementor-widget elementor-widget-text-editor\" data-id=\"5a9d891\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Engage customers proactively with our built-in feature, sending timely parcel status updates via email to keep them informed at every step.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c8a32b7 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"c8a32b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ec6ac8 elementor-widget elementor-widget-text-editor\" data-id=\"4ec6ac8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/helpcentre-sg.easyparcel.com\/support\/solutions\/folders\/9000195942\" class=\"sg-help-centre\" target=\"_blank\">Learn more on how EasyTrack work &gt;<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9f8959b e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"9f8959b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22e7715 elementor-widget elementor-widget-heading\" data-id=\"22e7715\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Parcel Status Meanings<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-26bcc1c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"26bcc1c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2bf6e9e elementor-widget elementor-widget-html\" data-id=\"2bf6e9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\r\n<html lang=\"en\">\r\n<head>\r\n  \r\n    <style>\r\n       \r\n\r\n        .status-heading {\r\n            background-color: #F9278E;\r\n            color: white;\r\n            padding: 15px;\r\n            text-align: center;\r\n        }\r\n\r\n        td {\r\n            padding: 12px 15px;\r\n            border-bottom: 1px solid #ddd;\r\n            vertical-align: top;\r\n        }\r\n\r\n        td:first-child {\r\n            width: 25%;\r\n        }\r\n\r\n        td:last-child {\r\n            width: 75%;\r\n        }\r\n\r\n        tr:nth-child(even) {\r\n            background-color: #f9f9f9;\r\n        }\r\n\r\n        tr:hover {\r\n            background-color: #f5f5f5;\r\n        }\r\n\r\n        .category-title {\r\n            font-weight: bold;\r\n            color: #F9278E;\r\n            margin-bottom: 8px;\r\n        }\r\n\r\n        .description {\r\n            line-height: 1.4;\r\n        }\r\n\r\n        h4 {\r\n            margin: 0;\r\n            padding: 0;\r\n        }\r\n    <\/style>\r\n<\/head>\r\n<body>\r\n    <div class=\"container\">\r\n        <table>\r\n            <thead>\r\n                <tr>\r\n                    <th class=\"status-heading\">Status<\/th>\r\n                    <th class=\"status-heading\">Its Meaning<\/th>\r\n                <\/tr>\r\n            <\/thead>\r\n            <tbody>\r\n                <tr>\r\n                    <td>\r\n                        <div class=\"category-title\">Scheduled (In Arrangement)<\/div>\r\n                    <\/td>\r\n                    <td>\r\n                        <div class=\"description\">This means that you have successfully booked a parcel and is already scheduled for next step.<\/div>\r\n                    <\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td>\r\n                        <div class=\"category-title\">Pending For Collection<\/div>\r\n                    <\/td>\r\n                    <td>\r\n                        <div class=\"description\">This means that your parcel is ready to be picked up by your chosen courier service.<\/div>\r\n                    <\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td>\r\n                        <div class=\"category-title\">Delivery On Hold<\/div>\r\n                    <\/td>\r\n                    <td>\r\n                        <div class=\"description\">This means that your parcel delivery is being held on for a while until the next step can be carry out.<\/div>\r\n                    <\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td>\r\n                        <div class=\"category-title\">Collected<\/div>\r\n                    <\/td>\r\n                    <td>\r\n                        <div class=\"description\">This means that your parcel has been collected by your courier.<\/div>\r\n                    <\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td>\r\n                        <div class=\"category-title\">Drop Off<\/div>\r\n                    <\/td>\r\n                    <td>\r\n                        <div class=\"description\">This means that you have chosen the drop off option for your parcel.<\/div>\r\n                    <\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td>\r\n                        <div class=\"category-title\">In Transit<\/div>\r\n                    <\/td>\r\n                    <td>\r\n                        <div class=\"description\">This means that your parcel is already in its way to your receiver.<\/div>\r\n                    <\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td>\r\n                        <div class=\"category-title\">Delivered<\/div>\r\n                    <\/td>\r\n                    <td>\r\n                        <div class=\"description\">This means that your parcel has been successfully arrived at its destination (your receiver's location).<\/div>\r\n                    <\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td>\r\n                        <div class=\"category-title\">Returned<\/div>\r\n                    <\/td>\r\n                    <td>\r\n                        <div class=\"description\">This means that your parcel has been successfully returned to your address (sender's address).<\/div>\r\n                    <\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td>\r\n                        <div class=\"category-title\">Cancelled<\/div>\r\n                    <\/td>\r\n                    <td>\r\n                        <div class=\"description\">This means that you have cancelled your delivery booking.<\/div>\r\n                    <\/td>\r\n                <\/tr>\r\n                <tr>\r\n                    <td>\r\n                        <div class=\"category-title\">Admin Cancel<\/div>\r\n                    <\/td>\r\n                    <td>\r\n                        <div class=\"description\">This means that the EasyParcel has cancelled your parcel booking.<\/div>\r\n                    <\/td>\r\n                <\/tr>\r\n            <\/tbody>\r\n        <\/table>\r\n    <\/div>\r\n<\/body>\r\n<\/html>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-862a577 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"862a577\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bc9b9c4 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"bc9b9c4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d03eff2 elementor-widget elementor-widget-image\" data-id=\"d03eff2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2024\/05\/frequently-asked-questions.webp\" class=\"attachment-full size-full wp-image-53765\" alt=\"\" srcset=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2024\/05\/frequently-asked-questions.webp 1080w, https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2024\/05\/frequently-asked-questions-300x300.webp 300w, https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2024\/05\/frequently-asked-questions-1024x1024.webp 1024w, https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2024\/05\/frequently-asked-questions-150x150.webp 150w, https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2024\/05\/frequently-asked-questions-768x768.webp 768w, https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2024\/05\/frequently-asked-questions-650x650.webp 650w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-35c196b e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"35c196b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78b1fbe elementor-widget elementor-widget-html\" data-id=\"78b1fbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\r\n    .faq-container {\r\n        font-family: 'Lato', sans-serif;\r\n        max-width: 800px;\r\n        margin: 0 auto;\r\n    }\r\n    .faq-title {\r\n        font-size: 24px;\r\n        font-weight: 700;\r\n        color: #333;\r\n        margin-bottom: 30px;\r\n        text-align: left;\r\n    }\r\n    .faq-item {\r\n        padding: 20px 0;\r\n        background-color: white;\r\n    }\r\n    .faq-question {\r\n        display: flex;\r\n        justify-content: space-between;\r\n        align-items: center;\r\n        cursor: pointer;\r\n        font-weight: 700;\r\n        font-size: 16px;\r\n        color: #666666;\r\n        background-color: transparent;\r\n        outline: none;\r\n        user-select: none;\r\n        transition: color 0.2s ease;\r\n    }\r\n    .faq-item.active .faq-question {\r\n        color: #000000;\r\n    }\r\n    .faq-question:focus,\r\n    .faq-question:active {\r\n        background-color: transparent !important;\r\n        outline: none;\r\n    }\r\n    .faq-answer {\r\n        max-height: 0;\r\n        overflow: hidden;\r\n        transition: max-height 0.3s ease-out;\r\n        color: #666;\r\n        line-height: 1.6;\r\n        padding-right: 30px;\r\n        background-color: white;\r\n    }\r\n    .faq-answer.active {\r\n        max-height: 200px;\r\n        margin-top: 15px;\r\n    }\r\n    .faq-toggle {\r\n        position: relative;\r\n        width: 20px;\r\n        height: 20px;\r\n        transition: transform 0.3s ease;\r\n    }\r\n    .faq-toggle::after {\r\n        content: '';\r\n        display: inline-block;\r\n        width: 8px;\r\n        height: 8px;\r\n        border-right: 2px solid #666;\r\n        border-bottom: 2px solid #666;\r\n        transform: rotate(45deg);\r\n        margin-left: 8px;\r\n        transition: transform 0.3s ease;\r\n    }\r\n    .faq-item.active .faq-toggle::after {\r\n        transform: rotate(225deg);\r\n        margin-top: 4px;\r\n    }\r\n<\/style>\r\n\r\n<div class=\"faq-container\">\r\n    <h2 class=\"faq-title\">Frequently Asked Questions (FAQ)<\/h2>\r\n\r\n    <div class=\"faq-item active\">\r\n        <div class=\"faq-question\">\r\n            <span>How to track Airpak Express parcel?<\/span>\r\n            <div class=\"faq-toggle\"><\/div>\r\n        <\/div>\r\n        <div class=\"faq-answer active\">\r\n            All you need is to key in your Airpak Express tracking number inside the column of our parcel tracker. Enter up to 15 Airpak Express tracking numbers. Separate with a semicolon (;) or return (enter).\r\n        <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"faq-item\">\r\n        <div class=\"faq-question\">\r\n            <span>Why is my Airpak Express parcel tracking number not working?<\/span>\r\n            <div class=\"faq-toggle\"><\/div>\r\n        <\/div>\r\n        <div class=\"faq-answer\">\r\n            <strong>Scenario 1:<\/strong> <span style=\"font-weight: 400;\">You insert the incorrect Airpak Express tracking number.<\/span>\r\n            <br><strong>Scenario 2:<\/strong> <span style=\"font-weight: 400;\">Your parcel has been cancelled.<\/span>\r\n            <br><span style=\"font-weight: 400;\">Feel free to reach out to our <a class=\"sg-help-centre\" href=\"https:\/\/helpcentre-sg.easyparcel.com\/support\/home\" target=\"_blank\" rel=\"noopener\">Help Centre<\/a> or contact us <\/span><a class=\"sg-contact-us\" href=\"\/sg\/contact-us\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">here<\/span><\/a><span style=\"font-weight: 400;\"> if you need help for your shipment status.<\/span>\r\n        <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"faq-item\">\r\n        <div class=\"faq-question\">\r\n            <span>Is the Airpak Express tracking number case sensitive?<\/span>\r\n            <div class=\"faq-toggle\"><\/div>\r\n        <\/div>\r\n        <div class=\"faq-answer\">\r\n            No, it is not. You may key in the Airpak Express tracking number without uppercase\/ lowercase; it works for both.\r\n        <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"faq-item\">\r\n        <div class=\"faq-question\">\r\n            <span>What if my Airpak Express parcel tracking status is not up-to-date?<\/span>\r\n            <div class=\"faq-toggle\"><\/div>\r\n        <\/div>\r\n        <div class=\"faq-answer\">\r\n            If your Airpak Express parcel status does not receive an update within 3 working days you may reach us out at <a class=\"sg-contact-us\" href=\"\/sg\/contact-us\/\" target=\"_blank\" rel=\"noopener\">customer service<\/a>.\r\n        <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"faq-item\">\r\n        <div class=\"faq-question\">\r\n            <span>How can I integrate with EasyTrack Tools?<\/span>\r\n            <div class=\"faq-toggle\"><\/div>\r\n        <\/div>\r\n        <div class=\"faq-answer\">\r\n            You may integrate <a href=\"\/sg\/widgets\/\">EasyTrack tools<\/a> with any eCommerce builder you are using, we support up to 80+ eCommerce Extensions.\r\n        <\/div>\r\n    <\/div>\r\n\r\n<\/div>\r\n\r\n<script>\r\n    document.addEventListener('DOMContentLoaded', function() {\r\n        const faqQuestions = document.querySelectorAll('.faq-question');\r\n        faqQuestions.forEach(question => {\r\n            question.addEventListener('click', function () {\r\n                const faqItem = this.parentElement;\r\n                const answer = this.nextElementSibling;\r\n                \/\/ Close all other open items\r\n                document.querySelectorAll('.faq-item').forEach(item => {\r\n                    if (item !== faqItem) {\r\n                        item.classList.remove('active');\r\n                        item.querySelector('.faq-answer').classList.remove('active');\r\n                    }\r\n                });\r\n                \/\/ Toggle current item\r\n                faqItem.classList.toggle('active');\r\n                answer.classList.toggle('active');\r\n            });\r\n        });\r\n    });\r\n<\/script>\r\n\r\n<script type=\"application\/ld+json\">\r\n{\r\n  \"@context\": \"https:\/\/schema.org\",\r\n  \"@type\": \"FAQPage\",\r\n  \"mainEntity\": [\r\n    {\r\n      \"@type\": \"Question\",\r\n      \"name\": \"How to track Airpak Express parcel?\",\r\n      \"acceptedAnswer\": {\r\n        \"@type\": \"Answer\",\r\n        \"text\": \"All you need is to key in your Airpak Express tracking number inside the column of our parcel tracker. Enter up to 15 Airpak Express tracking numbers. Separate with a semicolon (;) or return (enter).\"\r\n      }\r\n    },\r\n    {\r\n      \"@type\": \"Question\",\r\n      \"name\": \"Why is my Airpak Express parcel tracking number not working?\",\r\n      \"acceptedAnswer\": {\r\n        \"@type\": \"Answer\",\r\n        \"text\": \"Scenario 1: You insert the incorrect Airpak Express tracking number. Scenario 2: Your parcel has been cancelled. Feel free to reach out to our Help Centre or contact us here if you need help for your shipment status.\"\r\n      }\r\n    },\r\n    {\r\n      \"@type\": \"Question\",\r\n      \"name\": \"Is the Airpak Express tracking number case sensitive?\",\r\n      \"acceptedAnswer\": {\r\n        \"@type\": \"Answer\",\r\n        \"text\": \"No, it is not. You may key in the Airpak Express tracking number without uppercase\/ lowercase; it works for both.\"\r\n      }\r\n    },\r\n    {\r\n      \"@type\": \"Question\",\r\n      \"name\": \"What if my Airpak Express parcel tracking status is not up-to-date?\",\r\n      \"acceptedAnswer\": {\r\n        \"@type\": \"Answer\",\r\n        \"text\": \"If your Airpak Express parcel status does not receive an update within 3 working days you may reach us out at customer service.\"\r\n      }\r\n    },\r\n    {\r\n      \"@type\": \"Question\",\r\n      \"name\": \"How can I integrate with EasyTrack Tools?\",\r\n      \"acceptedAnswer\": {\r\n        \"@type\": \"Answer\",\r\n        \"text\": \"You may integrate EasyTrack tools with any eCommerce builder you are using, we support up to 80+ eCommerce Extensions.\"\r\n      }\r\n    }\r\n  ]\r\n}\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67aae508 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"67aae508\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-528e423e e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"528e423e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7b70f164 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"7b70f164\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae53f1e elementor-widget elementor-widget-text-editor\" data-id=\"ae53f1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-page-id=\"PO6IdfTjNoQhPRxHTvYlJvaWgxg\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-PeR6dItVponWwHxuDzMlC1FPgIf\"><div data-page-id=\"PO6IdfTjNoQhPRxHTvYlJvaWgxg\" data-lark-html-role=\"root\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-PeR6dItVponWwHxuDzMlC1FPgIf\"><h2 class=\"ace-line ace-line old-record-id-KMgidSy05o3su8xJsJIl6kwYgme\">Never Lose Sight of Your Shipment<\/h2><div class=\"ace-line ace-line old-record-id-KMgidSy05o3su8xJsJIl6kwYgme\"><p>Keep track of your Airpak parcel with accurate tracking updates and delivery notifications through EasyTrack.<\/p><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1aa6f170 primary-filled-md elementor-widget elementor-widget-button\" data-id=\"1aa6f170\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/go.easyparcel.com\/VBLSRd\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Check Parcel Status<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-303cff70 e-con-full cta-img-container e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"303cff70\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f8eba32 cta-img elementor-widget elementor-widget-image\" data-id=\"2f8eba32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2025\/09\/adam-ready-to-join.webp\" class=\"attachment-large size-large wp-image-91626\" alt=\"\" srcset=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2025\/09\/adam-ready-to-join.webp 800w, https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2025\/09\/adam-ready-to-join-300x300.webp 300w, https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2025\/09\/adam-ready-to-join-150x150.webp 150w, https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2025\/09\/adam-ready-to-join-768x768.webp 768w, https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2025\/09\/adam-ready-to-join-650x650.webp 650w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Enter Your Airpak Express Tracking Number Track Airpak Express Shipments http:\/\/www.airpak-express.com\/ cs.manager@airpak-express.com Separate with a semicolon (;) or return (enter). Track Parcel Frequently Asked Questions (FAQ) How to track Airpak Express parcel? All you need is to key in your Airpak Express tracking number inside the column of our parcel tracker. Enter up to 15 Airpak Express tracking numbers. Separate with a semicolon (;) or return (enter). Why is my Airpak Express parcel tracking number not working? Scenario 1: You insert the incorrect Airpak Express tracking number. Scenario 2: Your parcel has been cancelled. Feel free to reach out to our Help Centre or contact us here if you need help for your shipment status. Is the Airpak Express tracking number case sensitive? No, it is not. You may key in the Airpak Express tracking number without uppercase\/ lowercase; it works for both. What if my Airpak Express parcel tracking status is not up-to-date? If your Airpak Express parcel status does not receive an update within 3 working days you may reach us out at customer service. How can I integrate with EasyTrack Tools? You may integrate EasyTrack tools with any eCommerce builder you are using, we support up to 80+ eCommerce Extensions. Never Lose Sight of Your Shipment Keep track of your Airpak parcel with accurate tracking updates and delivery notifications through EasyTrack. Check Parcel Status<\/p>\n","protected":false},"author":6,"featured_media":43672,"parent":3837,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6112","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Airpak Tracking \u2013 Trace Your Parcel with 1 Click<\/title>\n<meta name=\"description\" content=\"Enter your Airpak tracking number for 100% accurate Airpak parcel status updates. Track up to 15 Airpak shipments at once.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/easyparcel.com\/sg\/easytrack\/airpak\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Track Airpak Express Tracking Number | EasyParcel Singapore\" \/>\n<meta property=\"og:description\" content=\"Track Airpak Express parcel and 80+ courier services in one platform - EasyTrack. Track up to 15 Airpak Express tracking numbers at once.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/easyparcel.com\/sg\/easytrack\/airpak\/\" \/>\n<meta property=\"og:site_name\" content=\"EasyParcel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/easyParcel.my\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-11T02:03:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2023\/06\/Singapore-top-courier-parcel-tracking-platform-easytrack-square.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Track Airpak Express Tracking Number | EasyParcel Singapore\" \/>\n<meta name=\"twitter:description\" content=\"Track Airpak Express parcel and 80+ courier services in one platform - EasyTrack. Track up to 15 Airpak Express tracking numbers at once.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2023\/06\/Singapore-top-courier-parcel-tracking-platform-easytrack-long.png\" \/>\n<meta name=\"twitter:site\" content=\"@easyparcel\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"25 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/easytrack\\\/airpak\\\/\",\"url\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/easytrack\\\/airpak\\\/\",\"name\":\"Airpak Tracking \u2013 Trace Your Parcel with 1 Click\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/easytrack\\\/airpak\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/easytrack\\\/airpak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ep-website-media.s3.ap-southeast-1.amazonaws.com\\\/sg\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Singapore-top-courier-parcel-tracking-platform-easytrack-square.png\",\"datePublished\":\"2022-04-14T03:27:53+00:00\",\"dateModified\":\"2026-06-11T02:03:37+00:00\",\"description\":\"Enter your Airpak tracking number for 100% accurate Airpak parcel status updates. Track up to 15 Airpak shipments at once.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/easytrack\\\/airpak\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/easyparcel.com\\\/sg\\\/easytrack\\\/airpak\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/easytrack\\\/airpak\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ep-website-media.s3.ap-southeast-1.amazonaws.com\\\/sg\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Singapore-top-courier-parcel-tracking-platform-easytrack-square.png\",\"contentUrl\":\"https:\\\/\\\/ep-website-media.s3.ap-southeast-1.amazonaws.com\\\/sg\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Singapore-top-courier-parcel-tracking-platform-easytrack-square.png\",\"width\":800,\"height\":800,\"caption\":\"Singapore Top One Courier Parcel Tracking Platform\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/easytrack\\\/airpak\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EasyTrack\",\"item\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/easytrack\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Airpak Express\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/#website\",\"url\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/\",\"name\":\"EasyParcel\",\"description\":\"EasyParcel - Delivery Made Easy\",\"publisher\":{\"@id\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/#organization\",\"name\":\"EasyParcel\",\"url\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logo_horizontal.svg\",\"contentUrl\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logo_horizontal.svg\",\"width\":365,\"height\":95,\"caption\":\"EasyParcel\"},\"image\":{\"@id\":\"https:\\\/\\\/easyparcel.com\\\/sg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/easyParcel.my\",\"https:\\\/\\\/x.com\\\/easyparcel\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/EasyParcelBayanLepas\",\"https:\\\/\\\/www.instagram.com\\\/easyparcel.my\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Airpak Tracking \u2013 Trace Your Parcel with 1 Click","description":"Enter your Airpak tracking number for 100% accurate Airpak parcel status updates. Track up to 15 Airpak shipments at once.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/easyparcel.com\/sg\/easytrack\/airpak\/","og_locale":"en_US","og_type":"article","og_title":"Track Airpak Express Tracking Number | EasyParcel Singapore","og_description":"Track Airpak Express parcel and 80+ courier services in one platform - EasyTrack. Track up to 15 Airpak Express tracking numbers at once.","og_url":"https:\/\/easyparcel.com\/sg\/easytrack\/airpak\/","og_site_name":"EasyParcel","article_publisher":"https:\/\/www.facebook.com\/easyParcel.my","article_modified_time":"2026-06-11T02:03:37+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2023\/06\/Singapore-top-courier-parcel-tracking-platform-easytrack-square.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_title":"Track Airpak Express Tracking Number | EasyParcel Singapore","twitter_description":"Track Airpak Express parcel and 80+ courier services in one platform - EasyTrack. Track up to 15 Airpak Express tracking numbers at once.","twitter_image":"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2023\/06\/Singapore-top-courier-parcel-tracking-platform-easytrack-long.png","twitter_site":"@easyparcel","twitter_misc":{"Est. reading time":"25 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/easyparcel.com\/sg\/easytrack\/airpak\/","url":"https:\/\/easyparcel.com\/sg\/easytrack\/airpak\/","name":"Airpak Tracking \u2013 Trace Your Parcel with 1 Click","isPartOf":{"@id":"https:\/\/easyparcel.com\/sg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/easyparcel.com\/sg\/easytrack\/airpak\/#primaryimage"},"image":{"@id":"https:\/\/easyparcel.com\/sg\/easytrack\/airpak\/#primaryimage"},"thumbnailUrl":"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2023\/06\/Singapore-top-courier-parcel-tracking-platform-easytrack-square.png","datePublished":"2022-04-14T03:27:53+00:00","dateModified":"2026-06-11T02:03:37+00:00","description":"Enter your Airpak tracking number for 100% accurate Airpak parcel status updates. Track up to 15 Airpak shipments at once.","breadcrumb":{"@id":"https:\/\/easyparcel.com\/sg\/easytrack\/airpak\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/easyparcel.com\/sg\/easytrack\/airpak\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/easyparcel.com\/sg\/easytrack\/airpak\/#primaryimage","url":"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2023\/06\/Singapore-top-courier-parcel-tracking-platform-easytrack-square.png","contentUrl":"https:\/\/ep-website-media.s3.ap-southeast-1.amazonaws.com\/sg\/wp-content\/uploads\/2023\/06\/Singapore-top-courier-parcel-tracking-platform-easytrack-square.png","width":800,"height":800,"caption":"Singapore Top One Courier Parcel Tracking Platform"},{"@type":"BreadcrumbList","@id":"https:\/\/easyparcel.com\/sg\/easytrack\/airpak\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/easyparcel.com\/sg\/"},{"@type":"ListItem","position":2,"name":"EasyTrack","item":"https:\/\/easyparcel.com\/sg\/easytrack\/"},{"@type":"ListItem","position":3,"name":"Airpak Express"}]},{"@type":"WebSite","@id":"https:\/\/easyparcel.com\/sg\/#website","url":"https:\/\/easyparcel.com\/sg\/","name":"EasyParcel","description":"EasyParcel - Delivery Made Easy","publisher":{"@id":"https:\/\/easyparcel.com\/sg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/easyparcel.com\/sg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/easyparcel.com\/sg\/#organization","name":"EasyParcel","url":"https:\/\/easyparcel.com\/sg\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/easyparcel.com\/sg\/#\/schema\/logo\/image\/","url":"https:\/\/easyparcel.com\/sg\/wp-content\/uploads\/2022\/03\/logo_horizontal.svg","contentUrl":"https:\/\/easyparcel.com\/sg\/wp-content\/uploads\/2022\/03\/logo_horizontal.svg","width":365,"height":95,"caption":"EasyParcel"},"image":{"@id":"https:\/\/easyparcel.com\/sg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/easyParcel.my","https:\/\/x.com\/easyparcel","https:\/\/www.youtube.com\/c\/EasyParcelBayanLepas","https:\/\/www.instagram.com\/easyparcel.my\/"]}]}},"_links":{"self":[{"href":"https:\/\/easyparcel.com\/sg\/wp-json\/wp\/v2\/pages\/6112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyparcel.com\/sg\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/easyparcel.com\/sg\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/easyparcel.com\/sg\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/easyparcel.com\/sg\/wp-json\/wp\/v2\/comments?post=6112"}],"version-history":[{"count":52,"href":"https:\/\/easyparcel.com\/sg\/wp-json\/wp\/v2\/pages\/6112\/revisions"}],"predecessor-version":[{"id":116225,"href":"https:\/\/easyparcel.com\/sg\/wp-json\/wp\/v2\/pages\/6112\/revisions\/116225"}],"up":[{"embeddable":true,"href":"https:\/\/easyparcel.com\/sg\/wp-json\/wp\/v2\/pages\/3837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/easyparcel.com\/sg\/wp-json\/wp\/v2\/media\/43672"}],"wp:attachment":[{"href":"https:\/\/easyparcel.com\/sg\/wp-json\/wp\/v2\/media?parent=6112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}